{"id":25998,"date":"2021-12-23T15:32:48","date_gmt":"2021-12-23T04:32:48","guid":{"rendered":"https:\/\/creately.com\/blog\/?p=25998"},"modified":"2022-10-19T20:51:55","modified_gmt":"2022-10-19T09:51:55","slug":"guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos","status":"publish","type":"post","link":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/","title":{"rendered":"Guia de tipos de diagramas UML: aprenda sobre todos os tipos de diagramas UML com exemplos"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span style=\"font-weight: 400;\">UML significa Unified Modeling Language (Linguagem de Modelagem Unificada). \u00c9 uma linguagem rica para modelar solu\u00e7\u00f5es de software, estruturas de aplica\u00e7\u00e3o, comportamento do sistema e<\/span><a href=\"https:\/\/creately.com\/blog\/diagrams\/importance-of-business-process-modeling\/\"> <span style=\"font-weight: 400;\">processos de neg\u00f3cio<\/span><\/a><span style=\"font-weight: 400;\">. Existem <\/span><b>14 tipos de diagramas UML<\/b><span style=\"font-weight: 400;\"> para o ajudar a modelar estes comportamentos. Voc\u00ea pode diagramas UML online usando o nosso software, ou veja alguns exemplos de<\/span><a href=\"https:\/\/creately.com\/diagram-type\/templates\/uml-diagram\"> <span style=\"font-weight: 400;\">diagramas UML<\/span><\/a><span style=\"font-weight: 400;\"> na nossa comunidade de diagrama\u00e7\u00e3o.<\/span><\/p>\n<h3><b>Lista de tipos de diagramas UML<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Ent\u00e3o, quais s\u00e3o os diferentes <a href=\"https:\/\/creately.com\/pt\/diagram-type\/diagrama-de-sequ%c3%aancia\/\">tipos de diagramas UML<\/a>? Existem duas categorias principais: <\/span><b>diagramas de estrutura<\/b><span style=\"font-weight: 400;\"> e <\/span><b>diagramas comportamentais<\/b><span style=\"font-weight: 400;\">. Clique nos links para saber mais sobre um tipo espec\u00edfico de diagrama.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Diagramas de Estrutura<\/span>\n<ul>\n<li><a href=\"#ClassDiagram\">Diagrama de Classes<\/a><\/li>\n<li><a href=\"#ComponentDiagram\">Diagrama de componentes<\/a><\/li>\n<li><a href=\"#DeploymentDiagram\">Diagrama de Implanta\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"#ObjectDiagram\">Diagrama de objetos<\/a><\/li>\n<li><a href=\"#PackageDiagram\">Diagrama do pacote<\/a><\/li>\n<li><a href=\"#ProfileDiagram\">Diagrama de Perfil<\/a><\/li>\n<li><a href=\"#CompStrDiagram\">Diagrama de Estrutura Composta<\/a><\/li>\n<\/ul>\n<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Diagramas Comportamentais<\/span>\n<ul>\n<li><a href=\"#UseCaseDiagram\">Use o diagrama de caso<\/a><\/li>\n<li><a href=\"#ActivityDiagram\">Diagrama de atividades<\/a><\/li>\n<li><a href=\"#StateMachDiagram\">Diagrama da M\u00e1quina do Estado<\/a><\/li>\n<li><a href=\"#SequenceDiagram\">Diagrama de Sequ\u00eancia<\/a><\/li>\n<li><a href=\"#CommDiagram\">Diagrama de Comunica\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"#IntOverDiagram\">Diagrama de vis\u00e3o geral da intera\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"#TimingDiagram\">Diagrama de tempo<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<div><\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14651 size-large\" src=\"https:\/\/creately.com\/blog\/wp-content\/uploads\/2012\/02\/UML-Diagram-types-1-1024x658.png\" alt=\"Todos os 14 tipos de diagrama UMl categorizados em UML comportamental e estrutural\" width=\"800\" height=\"514\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/UML-Diagram-types-1-1024x658.png 1024w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/UML-Diagram-types-1-300x193.png 300w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/UML-Diagram-types-1.png 1541w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div>\n<p><b>Os diagramas de estrutura<\/b><span style=\"font-weight: 400;\"> mostram as coisas no sistema modelado. Em um termo mais t\u00e9cnico, eles mostram diferentes objetos em um sistema. <\/span><b>Os diagramas comportamentais<\/b><span style=\"font-weight: 400;\"> mostram o que deve acontecer num sistema. Eles descrevem como os objetos interagem uns com os outros para criar um sistema funcional.<\/span><\/p>\n<h3><a name=\"ClassDiagram\"><\/a>Diagrama de Classes<\/h3>\n<div>\n<p><span style=\"font-weight: 400;\">Os diagramas de classes s\u00e3o o principal componente de qualquer solu\u00e7\u00e3o orientada a objetos. Mostra as classes em um sistema, atributos e opera\u00e7\u00f5es de cada classe e a rela\u00e7\u00e3o entre cada classe.<\/span><\/p>\n<\/div>\n<div><\/div>\n<div>\n<p><span style=\"font-weight: 400;\">Na maioria das ferramentas de modelagem, uma classe tem tr\u00eas partes. Nome no topo, atributos no meio e opera\u00e7\u00f5es ou m\u00e9todos no fundo. Num sistema grande com muitas classes relacionadas, as classes s\u00e3o agrupadas para criar diagramas de classes. Diferentes rela\u00e7\u00f5es<\/span><a href=\"https:\/\/creately.com\/diagram-type\/article\/relationships-that-exist-between-classes\"> <span style=\"font-weight: 400;\">entre as classes<\/span><\/a><span style=\"font-weight: 400;\"> s\u00e3o mostradas por diferentes tipos de setas.<\/span><\/p>\n<\/div>\n<div><\/div>\n<div>\n<p><span style=\"font-weight: 400;\">Abaixo est\u00e1 uma imagem de um diagrama de classes. Siga o link abaixo para mais exemplos de diagramas de classes ou comece imediatamente com nossos <\/span><a href=\"https:\/\/creately.com\/diagram-type\/templates\/class-diagram\"><span style=\"font-weight: 400;\">modelos de diagrama de classes.<\/span><\/a><\/p>\n<\/div>\n<p><a href=\"https:\/\/creately.com\/demo-start\/?tempId=gsxncbybu\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14652 size-full\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Class-diagram.jpg\" alt=\"Diagrama de classes, o tipo mais popular de diagrama UML\" width=\"770\" height=\"501\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Class-diagram.jpg 770w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Class-diagram-300x195.jpg 300w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/a> <span style=\"font-weight: 400;\">Clique na imagem para editar o diagrama de classes acima (abre em nova janela)<\/span><\/p>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/creately.com\/diagram-community\/examples\/t\/class-diagram\"><b>Obtenha mais exemplos de diagrama de classes UML &gt;&gt;<\/b><\/a><\/h3>\n<h3><a name=\"ComponentDiagram\"><\/a>Diagrama de componentes<\/h3>\n<p><span style=\"font-weight: 400;\">Um diagrama de componentes mostra a rela\u00e7\u00e3o estrutural dos componentes de um sistema de software. Estes s\u00e3o utilizados principalmente quando se trabalha com sistemas complexos com muitos componentes. Os componentes se comunicam uns com os outros usando interfaces. As interfaces s\u00e3o ligadas atrav\u00e9s de conectores. A imagem abaixo mostra um diagrama de componentes. <\/span><a href=\"https:\/\/creately.com\/demo-start\/?tempId=gqz0nrua1\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14653 size-full\" src=\"https:\/\/creately.com\/blog\/wp-content\/uploads\/2012\/02\/Component-Diagram.jpg\" alt=\"Modelo de diagrama de componentes com explica\u00e7\u00e3o\" width=\"770\" height=\"496\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Component-Diagram.jpg 770w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Component-Diagram-300x193.jpg 300w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/a> <span style=\"font-weight: 400;\">Voc\u00ea pode usar este modelo de diagrama de componentes clicando na imagem<\/span><\/p>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/creately.com\/diagram-community\/examples\/t\/component-diagram\"><b>Obtenha mais modelos de diagramas de componentes &gt;&gt;<\/b><\/a><\/h3>\n<h3><a name=\"DeploymentDiagram\"><\/a>Diagrama de Implanta\u00e7\u00e3o<\/h3>\n<p><span style=\"font-weight: 400;\">Um<\/span> <a href=\"https:\/\/creately.com\/blog\/diagrams\/deployment-diagram-tutorial\/\"><span style=\"font-weight: 400;\">diagrama de implanta\u00e7\u00e3o<\/span><\/a><span style=\"font-weight: 400;\"> mostra o hardware do seu sistema e o software nesse hardware. Os diagramas de implanta\u00e7\u00e3o s\u00e3o \u00fateis quando a sua solu\u00e7\u00e3o de software \u00e9 implantada em v\u00e1rias m\u00e1quinas, tendo cada uma delas uma configura\u00e7\u00e3o \u00fanica. Abaixo est\u00e1 um exemplo de diagrama de implanta\u00e7\u00e3o. <\/span><a href=\"https:\/\/creately.com\/demo-start\/?tempId=l459P6Rjd2A\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14654 size-full\" src=\"https:\/\/creately.com\/blog\/wp-content\/uploads\/2012\/02\/Deployment-Diagram.jpg\" alt=\"Modelo de diagrama de implanta\u00e7\u00e3o\" width=\"770\" height=\"495\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Deployment-Diagram.jpg 770w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Deployment-Diagram-300x193.jpg 300w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/a> <span style=\"font-weight: 400;\">Clique na imagem para usar este diagrama de implanta\u00e7\u00e3o como modelo<\/span><\/p>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/creately.com\/diagram-community\/examples\/t\/deployment-diagram\"><b>Obtenha Mais Modelos de Diagramas de Implanta\u00e7\u00e3o &gt;&gt;<\/b><\/a><\/h3>\n<h3><a name=\"ObjectDiagram\"><\/a>Diagrama de objetos<\/h3>\n<p><span style=\"font-weight: 400;\">Os <\/span><a href=\"https:\/\/creately.com\/pt\/lp\/ferramenta-de-diagrama-de-objetos\"><span style=\"font-weight: 400;\">diagramas de objetos<\/span><\/a><span style=\"font-weight: 400;\">, \u00e0s vezes chamados de diagramas de inst\u00e2ncia, s\u00e3o muito semelhantes aos<\/span><a href=\"https:\/\/creately.com\/blog\/diagrams\/class-diagram-tutorial\/\"> <span style=\"font-weight: 400;\">diagramas de classes<\/span><\/a><span style=\"font-weight: 400;\">. Como os diagramas de classes, eles tamb\u00e9m mostram a rela\u00e7\u00e3o entre objetos, mas usam exemplos do mundo real. Eles mostram como ser\u00e1 um sistema em um determinado momento. Como h\u00e1 dados dispon\u00edveis nos objetos, eles s\u00e3o usados para explicar rela\u00e7\u00f5es complexas entre objetos. <\/span><a href=\"https:\/\/creately.com\/demo-start\/?tempId=gsxghfo2f\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14655 size-full\" src=\"https:\/\/creately.com\/blog\/wp-content\/uploads\/2012\/02\/Object-Diagram.jpg\" alt=\"Modelo de diagrama de objetos\" width=\"770\" height=\"409\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Object-Diagram.jpg 770w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Object-Diagram-300x159.jpg 300w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/a> <span style=\"font-weight: 400;\">Clique na imagem para usar o diagrama de objetos como modelo<\/span><\/p>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/creately.com\/diagram-community\/popular\/t\/object-diagram\"><b>Obter mais modelos de diagramas de objetos &gt;&gt;<\/b><\/a><\/h3>\n<h3><a name=\"PackageDiagram\"><\/a>Diagrama do pacote<\/h3>\n<p><span style=\"font-weight: 400;\">Como o nome sugere, um diagrama de pacotes mostra as depend\u00eancias entre os diferentes pacotes de um sistema. Confira os artigo wiki para saber mais sobre as depend\u00eancias e elementos encontrados nos diagramas de pacotes.<\/span><br \/>\n<a href=\"https:\/\/creately.com\/creately-start?tempID=j5xitrro1\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14657 size-full\" src=\"https:\/\/creately.com\/blog\/wp-content\/uploads\/2012\/02\/Package-Diagram.jpg\" alt=\"Exemplo de diagrama de pacotes UML\" width=\"770\" height=\"496\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Package-Diagram.jpg 770w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Package-Diagram-300x193.jpg 300w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/a><\/p>\n<h3><a name=\"ProfileDiagram\"><\/a>Diagrama de Perfil<\/h3>\n<p><span style=\"font-weight: 400;\">O diagrama de perfil \u00e9 um novo tipo de diagrama introduzido no UML 2. Este \u00e9 um tipo de diagrama que \u00e9 muito raramente utilizado em qualquer especifica\u00e7\u00e3o. Para mais modelos de diagramas de perfil, visite a nossa<a href=\"https:\/\/creately.com\/diagram-community\/all?term=Profile%2520Diagram\"> comunidade de diagramas.<\/a><\/span><br \/>\n<a href=\"https:\/\/creately.com\/demo-start\/?tempId=j6dbkbqz2\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14658 size-full\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Profile-Diagram.jpg\" alt=\"Diagrama de perfil UML\" width=\"770\" height=\"496\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Profile-Diagram.jpg 770w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Profile-Diagram-300x193.jpg 300w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/a><\/p>\n<h3><a name=\"CompStrDiagram\"><\/a>Diagrama de Estrutura Composta<\/h3>\n<p><span style=\"font-weight: 400;\">Os diagramas de estrutura compostos s\u00e3o usados para mostrar a estrutura interna de uma classe. Alguns dos<\/span><a href=\"https:\/\/creately.com\/diagram-community\/all?term=composite\"> <span style=\"font-weight: 400;\">diagramas de estrutura comuns est\u00e3o aqui.<\/span><\/a><br \/>\n<a href=\"https:\/\/creately.com\/demo-start\/?tempId=j5xitrro2\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14659 size-full\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Composite-Structure-Diagram.jpg\" alt=\"Diagrama da estrutura composta UML desenhado usando Creately\" width=\"770\" height=\"496\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Composite-Structure-Diagram.jpg 770w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Composite-Structure-Diagram-300x193.jpg 300w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/a><\/p>\n<h3><a name=\"UseCaseDiagram\"><\/a>Use o diagrama de caso<\/h3>\n<p><span style=\"font-weight: 400;\">Como o<\/span><a href=\"https:\/\/creately.com\/blog\/diagrams\/which-diagram-to-use\/\"> <span style=\"font-weight: 400;\">tipo de diagrama<\/span><\/a><span style=\"font-weight: 400;\"> mais conhecido dos tipos de UML comportamentais,<\/span><a href=\"https:\/\/creately.com\/diagram-community\/popular\/t\/use-case\"><span style=\"font-weight: 400;\"> diagramas de caso de uso<\/span><\/a><span style=\"font-weight: 400;\"> d\u00e3o uma vis\u00e3o gr\u00e1fica dos atores envolvidos em um sistema, diferentes fun\u00e7\u00f5es necess\u00e1rias para esses atores e como essas diferentes fun\u00e7\u00f5es interagem. \u00c9 um \u00f3timo ponto de partida para qualquer discuss\u00e3o de projeto porque voc\u00ea pode identificar facilmente os principais atores envolvidos e os principais processos do sistema. Voc\u00ea pode<\/span><a href=\"https:\/\/creately.com\/diagram-type\/use-case\"> <span style=\"font-weight: 400;\">criar diagramas de caso de uso<\/span><\/a><span style=\"font-weight: 400;\"> usando nossa ferramenta e\/ou come\u00e7ar imediatamente usando nossos<\/span><a href=\"https:\/\/creately.com\/blog\/examples\/use-case-templates-uml\/\"> <span style=\"font-weight: 400;\">modelos de caso de uso<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><a href=\"https:\/\/creately.com\/blog\/diagrams\/use-case-diagram-relationships\/\"><span style=\"font-weight: 400;\"> Rela\u00e7\u00f5es de Diagramas de caso de uso explicadas com exemplos<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<div id=\"attachment_14662\" style=\"width: 780px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/creately.com\/demo-start\/?tempId=gsxncbyb2\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14662\" class=\"wp-image-14662 size-full\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Use-Case-Diagram.jpg\" alt=\"Use o desenho do diagrama de caso usando Creately\" width=\"770\" height=\"594\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Use-Case-Diagram.jpg 770w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Use-Case-Diagram-300x231.jpg 300w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/a><p id=\"caption-attachment-14662\" class=\"wp-caption-text\"><span style=\"font-weight: 400;\">Clique na imagem para editar este modelo<\/span><\/p><\/div>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/creately.com\/diagram-community\/examples\/t\/use-case\"><b>Obtenha mais exemplos de diagramas de casos de uso &gt;&gt;<\/b><\/a><\/h3>\n<h3><a name=\"ActivityDiagram\"><\/a>Diagrama de atividades<\/h3>\n<p><span style=\"font-weight: 400;\">Os diagramas de atividade representam fluxos de trabalho de uma forma gr\u00e1fica. Podem ser utilizados para descrever o fluxo de trabalho empresarial ou o fluxo de trabalho operacional de qualquer componente de um sistema. \u00c0s vezes, <\/span><a href=\"https:\/\/creately.com\/diagram-community\/popular\/t\/activity-diagram\"><span style=\"font-weight: 400;\">diagramas de atividade<\/span><\/a><span style=\"font-weight: 400;\"> s\u00e3o usados como uma alternativa aos diagramas de m\u00e1quina do Estado. Confira este artigo wiki para aprender sobre s\u00edmbolos e uso de diagramas de atividades. Voc\u00ea tamb\u00e9m pode consultar este<\/span><a href=\"https:\/\/creately.com\/blog\/diagrams\/activity-diagram-tutorial\/\"> <span style=\"font-weight: 400;\">guia f\u00e1cil<\/span><\/a><span style=\"font-weight: 400;\"> para diagramas de atividades.<\/span><\/p>\n<h3><a href=\"https:\/\/creately.com\/demo-start\/?tempId=4j1WGEtVzwJ\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14663 size-full\" src=\"https:\/\/creately.com\/blog\/wp-content\/uploads\/2012\/02\/Activity-Diagram.jpg\" alt=\"Diagrama de atividades desenhado usando Creately\" width=\"770\" height=\"370\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Activity-Diagram.jpg 770w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Activity-Diagram-300x144.jpg 300w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/a><\/h3>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/creately.com\/diagram-community\/examples\/t\/activity-diagram\"><b>Obtenha mais modelos de diagramas de atividades &gt;&gt;<\/b><\/a><\/h3>\n<h3><a name=\"StateMachDiagram\"><\/a>Diagrama da M\u00e1quina do Estado<\/h3>\n<p><a href=\"https:\/\/creately.com\/pt\/lp\/software-de-diagrama-de-estados\"><span style=\"font-weight: 400;\">Os diagramas das m\u00e1quinas de estado<\/span><\/a><span style=\"font-weight: 400;\"> s\u00e3o semelhantes aos diagramas de atividade, embora<\/span> <a href=\"https:\/\/creately.com\/diagram-type\/objects\/database-design\"><span style=\"font-weight: 400;\">as nota\u00e7\u00f5es<\/span><\/a><span style=\"font-weight: 400;\"> e o uso mudem um pouco. Por vezes s\u00e3o tamb\u00e9m conhecidos como<\/span> <a href=\"https:\/\/creately.com\/diagram\/example\/h1xtnwwh1\/New%20Facebook%20Login%20Activity%20Diagram\"><span style=\"font-weight: 400;\">diagramas de estados<\/span><\/a><span style=\"font-weight: 400;\"> ou<\/span><a href=\"https:\/\/creately.com\/diagram-community\/popular\/t\/state-chart\"> <span style=\"font-weight: 400;\">diagramas de gr\u00e1fico de estados<\/span><\/a><span style=\"font-weight: 400;\">. Estes s\u00e3o muito \u00fateis para descrever o comportamento de objetos que agem de forma diferente de acordo com o estado em que se encontram no momento. O diagrama da m\u00e1quina de estado abaixo mostra os estados e a\u00e7\u00f5es b\u00e1sicas.<\/span><a href=\"https:\/\/creately.com\/demo-start\/?tempId=bz8AGzoVTJr\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14664 size-full\" src=\"https:\/\/creately.com\/blog\/wp-content\/uploads\/2012\/02\/State-Machine-Diagram.jpg\" alt=\"Diagrama de m\u00e1quina do estado\" width=\"771\" height=\"581\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/State-Machine-Diagram.jpg 771w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/State-Machine-Diagram-300x226.jpg 300w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/a> <span style=\"font-weight: 400;\">Diagrama de Estado da M\u00e1quina em UML, por vezes referido como<\/span> <a href=\"https:\/\/creately.com\/diagram-community\/examples\/t\/state-chart\"><span style=\"font-weight: 400;\">diagrama de<\/span><\/a><span style=\"font-weight: 400;\"> Estado ou<\/span><a href=\"https:\/\/creately.com\/diagram-community\/examples\/t\/state-chart\"> <span style=\"font-weight: 400;\">diagrama de gr\u00e1fico de Estado<\/span><\/a><\/p>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/creately.com\/diagram-community\/examples\"><b>Obtenha mais exemplos de diagramas de estados &gt;&gt;<\/b><\/a><\/h3>\n<h3><a name=\"SequenceDiagram\"><\/a>Diagrama de Sequ\u00eancia<\/h3>\n<p><a href=\"https:\/\/creately.com\/diagram-community\/popular\/t\/sequence-diagram\"><span style=\"font-weight: 400;\">Os diagramas de sequ\u00eancia<\/span><\/a><span style=\"font-weight: 400;\"> em UML mostram como os objetos interagem uns com os outros e a ordem em que essas intera\u00e7\u00f5es ocorrem. \u00c9 importante notar que eles mostram as intera\u00e7\u00f5es para um determinado cen\u00e1rio. Os processos s\u00e3o representados verticalmente e as intera\u00e7\u00f5es s\u00e3o mostradas como setas. Este artigo explica<\/span><a href=\"https:\/\/creately.com\/blog\/diagrams\/the-basics-the-purpose-of-sequence-diagrams-part-1\/\"><span style=\"font-weight: 400;\"> o prop\u00f3sito e as bases dos diagramas de sequ\u00eancias<\/span><\/a><span style=\"font-weight: 400;\">. Confira tamb\u00e9m este<\/span> <a href=\"https:\/\/creately.com\/blog\/diagrams\/sequence-diagram-tutorial\/\"><span style=\"font-weight: 400;\">tutorial de Diagramas de Sequ\u00eancia<\/span><\/a><span style=\"font-weight: 400;\"> completo para saber mais sobre diagramas de sequ\u00eancia. Voc\u00ea tamb\u00e9m pode come\u00e7ar a desenhar instantaneamente usando nossos os<\/span><a href=\"https:\/\/creately.com\/diagram-community\/examples\/t\/sequence-diagram\"><span style=\"font-weight: 400;\"> modelos de diagramas de sequ\u00eancia<\/span><span style=\"font-weight: 400;\">. <\/span><\/a><a href=\"https:\/\/creately.com\/demo-start\/?tempId=gsx1cnemi\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14665 size-full\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Sequence-Diagram.jpg\" alt=\"Diagrama de seq\u00fc\u00eancias desenhado usando Creately\" width=\"770\" height=\"704\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Sequence-Diagram.jpg 770w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Sequence-Diagram-300x274.jpg 300w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/a> <span style=\"font-weight: 400;\">Diagrama de sequ\u00eancia desenhado usando<\/span> <span style=\"font-weight: 400;\">Creately.<\/span><\/p>\n<h3><a name=\"CommDiagram\"><\/a>Diagrama de Comunica\u00e7\u00e3o<\/h3>\n<p><span style=\"font-weight: 400;\">Em UML 1 foram chamados de<\/span><a href=\"https:\/\/creately.com\/diagram\/example\/jgi94q647\/Collaboration%20diagram\"> <span style=\"font-weight: 400;\">diagramas de colabora\u00e7\u00e3o<\/span><\/a><span style=\"font-weight: 400;\">. Os diagramas de comunica\u00e7\u00e3o s\u00e3o semelhantes aos diagramas de sequ\u00eancia, mas o foco est\u00e1 nas mensagens passadas entre objetos. A mesma informa\u00e7\u00e3o pode ser representada usando um diagrama de sequ\u00eancia e diferentes objetos. <\/span><a href=\"http:\/\/www.sparxsystems.com\/resources\/uml2_tutorial\/uml2_communicationdiagram.html\"><span style=\"font-weight: 400;\">Clique aqui<\/span><\/a><span style=\"font-weight: 400;\"> para compreender as diferen\u00e7as usando um exemplo.<\/span><br \/>\n<a href=\"https:\/\/creately.com\/demo-start\/?tempId=j634oa3j3\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14669 size-full\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Communication-Diagram.jpg\" alt=\"Diagrama de comunica\u00e7\u00e3o desenhado usando Creately\" width=\"771\" height=\"495\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Communication-Diagram.jpg 771w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Communication-Diagram-300x193.jpg 300w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/a><\/p>\n<h3><a name=\"IntOverDiagram\"><\/a>Diagrama de vis\u00e3o geral da intera\u00e7\u00e3o<\/h3>\n<p><span style=\"font-weight: 400;\">Os diagramas de s\u00edntese das intera\u00e7\u00f5es s\u00e3o muito semelhantes aos diagramas de atividades. Enquanto os diagramas de atividade mostram uma sequ\u00eancia de processos,<\/span><a href=\"https:\/\/creately.com\/diagram\/example\/hoz91qr31\/Interaction%20Overview%20Diagram\"> <span style=\"font-weight: 400;\">os diagramas de vis\u00e3o geral de<\/span><\/a><span style=\"font-weight: 400;\"> intera\u00e7\u00e3o mostram uma sequ\u00eancia de diagramas de intera\u00e7\u00e3o. S\u00e3o um conjunto de diagramas de intera\u00e7\u00e3o e a ordem em que acontecem. Como mencionado anteriormente, existem sete tipos de diagramas de intera\u00e7\u00e3o, portanto qualquer um deles pode ser um n\u00f3 em um<\/span><a href=\"https:\/\/creately.com\/diagram\/example\/jk0ehse02\/Interaction%20Overview%20Diagram\"> <span style=\"font-weight: 400;\">diagrama geral de <\/span><\/a> <a href=\"https:\/\/creately.com\/diagram\/example\/jk0ehse02\/Interaction%20Overview%20Diagram\"><span style=\"font-weight: 400;\">intera\u00e7\u00e3o.<\/span><\/a><br \/>\n<a href=\"https:\/\/creately.com\/demo-start\/?tempId=j634oa3j4\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14671 size-full\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Interaction-Overview-Diagram.jpg\" alt=\"Diagrama de vis\u00e3o geral de intera\u00e7\u00e3o UML desenhado usando Creately\" width=\"771\" height=\"857\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Interaction-Overview-Diagram.jpg 771w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Interaction-Overview-Diagram-270x300.jpg 270w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Interaction-Overview-Diagram-315x350.jpg 315w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/a><\/p>\n<h3><a name=\"TimingDiagram\"><\/a>Diagrama de tempo<\/h3>\n<p><span style=\"font-weight: 400;\">Os diagramas de tempo s\u00e3o muito semelhantes aos diagramas de sequ\u00eancia. Eles representam o comportamento dos objetos em um determinado per\u00edodo de tempo. Se for apenas um objeto, o diagrama \u00e9 simples. Mas, se houver mais de um objeto envolvido, um diagrama de tempo \u00e9 usado para mostrar intera\u00e7\u00f5es entre objetos durante esse per\u00edodo de tempo. Clique aqui para criar o seu<\/span><a href=\"https:\/\/creately.com\/pt\/lp\/software-de-diagrama-de-tempo\"> <span style=\"font-weight: 400;\">diagrama de tempo<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><br \/>\n<a href=\"https:\/\/creately.com\/demo-start\/?tempId=j634oa3j5\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14672 size-full\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Timing-Diagram.jpg\" alt=\"Diagrama temporizado UML desenhado usando Creately\" width=\"771\" height=\"832\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Timing-Diagram.jpg 771w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2012\/02\/Timing-Diagram-278x300.jpg 278w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Mencionamos acima todos os tipos de<\/span><a href=\"https:\/\/creately.com\/pt\/lp\/ferramenta-de-diagrama-uml\/\"> <span style=\"font-weight: 400;\">diagramas UML<\/span><\/a><span style=\"font-weight: 400;\">. A UML oferece muitos<\/span><a href=\"https:\/\/creately.com\/blog\/diagrams\/which-diagram-to-use\/\"> <span style=\"font-weight: 400;\">tipos de diagramas<\/span><\/a><span style=\"font-weight: 400;\">, e \u00e0s vezes dois diagramas podem explicar a mesma coisa usando nota\u00e7\u00f5es diferentes. Confira este post no blog para saber qual diagrama UML combina mais com voc\u00ea. Se voc\u00ea tiver alguma d\u00favida ou sugest\u00e3o, sinta-se \u00e0 vontade para deixar um coment\u00e1rio.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UML significa Unified Modeling Language (Linguagem de Modelagem Unificada). \u00c9 uma linguagem rica para modelar solu\u00e7\u00f5es de software, estruturas de aplica\u00e7\u00e3o, comportamento do sistema e processos de neg\u00f3cio. Existem 14 tipos de diagramas UML para o ajudar a modelar estes&#8230;<span class=\"continue-reading\"> <a href=\"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/\">Read More<\/a><\/span><\/p>\n","protected":false},"author":38,"featured_media":28486,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3274],"tags":[],"class_list":["post-25998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diagrama"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tipos de diagrama UML | Saiba mais sobre os 14 tipos de diagramas UML<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a todos os 14 tipos de diagramas UML com exemplos. O guia inclui imagens para todos os tipos de diagramas UML para que voc\u00ea possa identific\u00e1-los rapidamente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tipos de diagrama UML | Saiba mais sobre os 14 tipos de diagramas UML\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a todos os 14 tipos de diagramas UML com exemplos. O guia inclui imagens para todos os tipos de diagramas UML para que voc\u00ea possa identific\u00e1-los rapidamente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/\" \/>\n<meta property=\"og:site_name\" content=\"Creately Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/creately\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-23T04:32:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-19T09:51:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2021\/12\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lalindri Amunugama\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lalindri Amunugama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/\"},\"author\":{\"name\":\"Lalindri Amunugama\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#\\\/schema\\\/person\\\/cb4a421a55aa8a851260d92193524f26\"},\"headline\":\"Guia de tipos de diagramas UML: aprenda sobre todos os tipos de diagramas UML com exemplos\",\"datePublished\":\"2021-12-23T04:32:48+00:00\",\"dateModified\":\"2022-10-19T09:51:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/\"},\"wordCount\":1491,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2021\\\/12\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos.png\",\"articleSection\":[\"diagrama\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/\",\"url\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/\",\"name\":\"Tipos de diagrama UML | Saiba mais sobre os 14 tipos de diagramas UML\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2021\\\/12\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos.png\",\"datePublished\":\"2021-12-23T04:32:48+00:00\",\"dateModified\":\"2022-10-19T09:51:55+00:00\",\"description\":\"Conhe\u00e7a todos os 14 tipos de diagramas UML com exemplos. O guia inclui imagens para todos os tipos de diagramas UML para que voc\u00ea possa identific\u00e1-los rapidamente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2021\\\/12\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos.png\",\"contentUrl\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2021\\\/12\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos.png\",\"width\":512,\"height\":288},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/creately.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guia de tipos de diagramas UML: aprenda sobre todos os tipos de diagramas UML com exemplos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/creately.com\\\/blog\\\/\",\"name\":\"Creately Blog\",\"description\":\"Latest Product Updates and Tips on Working Visually\",\"publisher\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/creately.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#organization\",\"name\":\"Creately\",\"url\":\"https:\\\/\\\/creately.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2023\\\/01\\\/creately-logo-symbol.png\",\"contentUrl\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2023\\\/01\\\/creately-logo-symbol.png\",\"width\":430,\"height\":237,\"caption\":\"Creately\"},\"image\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/creately\",\"https:\\\/\\\/x.com\\\/creately\",\"https:\\\/\\\/www.instagram.com\\\/creately_app\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#\\\/schema\\\/person\\\/cb4a421a55aa8a851260d92193524f26\",\"name\":\"Lalindri Amunugama\",\"url\":\"https:\\\/\\\/creately.com\\\/blog\\\/author\\\/lalindri\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tipos de diagrama UML | Saiba mais sobre os 14 tipos de diagramas UML","description":"Conhe\u00e7a todos os 14 tipos de diagramas UML com exemplos. O guia inclui imagens para todos os tipos de diagramas UML para que voc\u00ea possa identific\u00e1-los rapidamente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/","og_locale":"en_US","og_type":"article","og_title":"Tipos de diagrama UML | Saiba mais sobre os 14 tipos de diagramas UML","og_description":"Conhe\u00e7a todos os 14 tipos de diagramas UML com exemplos. O guia inclui imagens para todos os tipos de diagramas UML para que voc\u00ea possa identific\u00e1-los rapidamente.","og_url":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/","og_site_name":"Creately Blog","article_publisher":"https:\/\/www.facebook.com\/creately","article_published_time":"2021-12-23T04:32:48+00:00","article_modified_time":"2022-10-19T09:51:55+00:00","og_image":[{"width":512,"height":288,"url":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2021\/12\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos.png","type":"image\/png"}],"author":"Lalindri Amunugama","twitter_misc":{"Written by":"Lalindri Amunugama","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/#article","isPartOf":{"@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/"},"author":{"name":"Lalindri Amunugama","@id":"https:\/\/creately.com\/blog\/#\/schema\/person\/cb4a421a55aa8a851260d92193524f26"},"headline":"Guia de tipos de diagramas UML: aprenda sobre todos os tipos de diagramas UML com exemplos","datePublished":"2021-12-23T04:32:48+00:00","dateModified":"2022-10-19T09:51:55+00:00","mainEntityOfPage":{"@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/"},"wordCount":1491,"commentCount":0,"publisher":{"@id":"https:\/\/creately.com\/blog\/#organization"},"image":{"@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/#primaryimage"},"thumbnailUrl":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2021\/12\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos.png","articleSection":["diagrama"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/","url":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/","name":"Tipos de diagrama UML | Saiba mais sobre os 14 tipos de diagramas UML","isPartOf":{"@id":"https:\/\/creately.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/#primaryimage"},"image":{"@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/#primaryimage"},"thumbnailUrl":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2021\/12\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos.png","datePublished":"2021-12-23T04:32:48+00:00","dateModified":"2022-10-19T09:51:55+00:00","description":"Conhe\u00e7a todos os 14 tipos de diagramas UML com exemplos. O guia inclui imagens para todos os tipos de diagramas UML para que voc\u00ea possa identific\u00e1-los rapidamente.","breadcrumb":{"@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/#primaryimage","url":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2021\/12\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos.png","contentUrl":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2021\/12\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos.png","width":512,"height":288},{"@type":"BreadcrumbList","@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/guia-de-tipos-de-diagramas-uml-aprenda-sobre-todos-os-tipos-de-diagramas-uml-com-exemplos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/creately.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Guia de tipos de diagramas UML: aprenda sobre todos os tipos de diagramas UML com exemplos"}]},{"@type":"WebSite","@id":"https:\/\/creately.com\/blog\/#website","url":"https:\/\/creately.com\/blog\/","name":"Creately Blog","description":"Latest Product Updates and Tips on Working Visually","publisher":{"@id":"https:\/\/creately.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/creately.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/creately.com\/blog\/#organization","name":"Creately","url":"https:\/\/creately.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/creately.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2023\/01\/creately-logo-symbol.png","contentUrl":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2023\/01\/creately-logo-symbol.png","width":430,"height":237,"caption":"Creately"},"image":{"@id":"https:\/\/creately.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/creately","https:\/\/x.com\/creately","https:\/\/www.instagram.com\/creately_app\/"]},{"@type":"Person","@id":"https:\/\/creately.com\/blog\/#\/schema\/person\/cb4a421a55aa8a851260d92193524f26","name":"Lalindri Amunugama","url":"https:\/\/creately.com\/blog\/author\/lalindri\/"}]}},"_links":{"self":[{"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/posts\/25998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/comments?post=25998"}],"version-history":[{"count":6,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/posts\/25998\/revisions"}],"predecessor-version":[{"id":28488,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/posts\/25998\/revisions\/28488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/media\/28486"}],"wp:attachment":[{"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/media?parent=25998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/categories?post=25998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/tags?post=25998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}