{"id":24709,"date":"2021-10-25T21:45:27","date_gmt":"2021-10-25T10:45:27","guid":{"rendered":"https:\/\/creately.com\/blog\/?p=24709"},"modified":"2022-05-10T21:19:11","modified_gmt":"2022-05-10T10:19:11","slug":"was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation","status":"publish","type":"post","link":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/","title":{"rendered":"Was ist Prozessdokumentation | Der einfache Leitfaden zur Prozessdokumentation"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><ul>\n<li>Mit dem Wachstum Ihres Unternehmens w\u00e4chst auch dessen Komplexit\u00e4t. Es sind mehr Schritte, mehr Personen und mehr Dinge involviert, die nicht immer auf die effizienteste Weise arrangiert werden k\u00f6nnen. Es mag entmutigend klingen, die Arbeitsweise Ihres Unternehmens zu \u00fcberdenken, aber es wird Ihnen zwangsl\u00e4ufig zu erheblichen Effizienzsteigerungen verhelfen. Die<a href=\"https:\/\/creately.com\/usage\/process-documentation-tools-templates\/\" target=\"_blank\" rel=\"noopener noreferrer\">Prozessdokumentation<\/a> ist der erste Schritt dazu! Dieser einfache Leitfaden f\u00fcr die Prozessdokumentation wird Ihnen dabei helfen, alles richtig zu machen. Lesen Sie weiter, um mehr zu erfahren;<\/li>\n<li><a href=\"#What\">Was ist Prozessdokumentation?<\/a><\/li>\n<li><a href=\"#Importance\">Warum tun Sie es? Die Bedeutung der Prozessdokumentation<\/a><\/li>\n<li><a href=\"#How\">Wie man einen Prozess dokumentiert<\/a><\/li>\n<li><a href=\"#Tips\">Tipps und Tricks: Bew\u00e4hrte Praktiken der Prozessdokumentation<\/a><\/li>\n<li><a href=\"#You\">Was ist f\u00fcr Sie drin? Vorteile der Prozessdokumentation<\/a><\/li>\n<li><a href=\"#Templates\">Easy Starter Prozess-Flussdiagramm-Vorlagen<\/a><\/li>\n<\/ul>\n<h3><a name=\"What\"><\/a>Was ist Prozessdokumentation?<\/h3>\n<p>Die Prozessdokumentation beschreibt detailliert, wie ein Gesch\u00e4ftsprozess auszuf\u00fchren ist. Sie umfasst alle Arten von Dokumenten, die einen Prozess unterst\u00fctzen, wie<\/p>\n<ul>\n<li><strong>richtlinien<\/strong><\/li>\n<li><a href=\"https:\/\/creately.com\/lp\/online-checklist-maker\/\"><strong>checklisten<\/strong><\/a><\/li>\n<li><strong>tutorials<\/strong><\/li>\n<li><strong>formulare<\/strong><\/li>\n<li><strong>screenshots<\/strong><\/li>\n<li><strong>links zu anderen Anwendungen<\/strong><\/li>\n<li><strong>prozesslandkarten<\/strong><\/li>\n<\/ul>\n<p>Es wird als Leitfaden verwendet, um Mitarbeitern auf allen Ebenen, einschlie\u00dflich Entscheidungstr\u00e4gern und Interessenvertretern, ein schnelles Verst\u00e4ndnis der Unternehmensprozesse zu erm\u00f6glichen.<\/p>\n<h3><a name=\"Importance\"><\/a>Warum es tun? : Die Bedeutung der Prozessdokumentation<\/h3>\n<p>Die Dokumentation eines Prozesses hilft Ihnen, 5 wichtige Dinge zu erreichen: 1)<strong> Hilft, Prozesse zu verbessern.<\/strong> Ermitteln Sie Engp\u00e4sse und Ineffizienzen, indem Sie die genauen Prozesse dokumentieren. Sie werden schnell sehen, welche Prozesse Sie verbessern oder abschaffen m\u00fcssen. 2)<strong> Hilft bei der Schulung von Mitarbeitern. <\/strong>Sie k\u00f6nnen Prozessdokumente verwenden, um neuen Mitarbeitern zu helfen, ihre Aufgaben zu verstehen und sich mit den Prozessen vertraut zu machen, an denen sie beteiligt sein werden. Selbst erfahrene Mitarbeiter k\u00f6nnen diese Dokumente immer wieder zu Rate ziehen, um sich zu vergewissern, dass sie den Prozess richtig ausf\u00fchren. 3) Es<strong> hilft, das Wissen des Unternehmens zu bewahren.<\/strong> F\u00fchren Sie Aufzeichnungen \u00fcber Prozesse, die nur einigen wenigen Fachleuten bekannt sind. Auf diese Weise k\u00f6nnen die Neuank\u00f6mmlinge die Arbeit problemlos fortsetzen, auch wenn sie ausscheiden. 4) Sie<strong> tr\u00e4gt zur Risikominderung und zur Aufrechterhaltung der betrieblichen Koh\u00e4renz<\/strong> bei. 5) Eine detaillierte Verfahrensdokumentation ist auch <strong>ein wesentlicher Bestandteil von Patenten und Gesch\u00e4ftsgeheimnissen<\/strong>.<\/p>\n<h3>Wer ist in die Prozessdokumentation involviert?<\/h3>\n<p>Bei der Prozessdokumentation gibt es 3 wichtige Rollen des Eigent\u00fcmers. In einigen F\u00e4llen kann ein und dieselbe Person alle drei Rollen \u00fcbernehmen. <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15286\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/Key-Process-Documentation-Roles.png\" alt=\"Schl\u00fcsselrollen der Prozessdokumentation\" width=\"829\" height=\"485\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/Key-Process-Documentation-Roles.png 829w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/Key-Process-Documentation-Roles-300x176.png 300w\" sizes=\"auto, (max-width: 829px) 100vw, 829px\" \/><\/p>\n<h3><a name=\"How\"><\/a>Wie man Prozesse dokumentiert<\/h3>\n<p>Die Verwendung einer schrittweisen Methode zur Dokumentation eines Prozesses hilft Ihnen, diesen schnell zu erledigen.<\/p>\n<h4>Schritt 1: Identifizieren und benennen Sie den Prozess<\/h4>\n<p style=\"padding-left: 30px;\">\u00dcberlegen Sie, welchen Prozess Sie zuerst dokumentieren wollen. Bestimmen Sie den Zweck (warum und wie der Prozess der Organisation n\u00fctzt) und geben Sie eine kurze Beschreibung des Prozesses.<\/p>\n<h4>Schritt 2: Definieren Sie den Prozessumfang<\/h4>\n<p style=\"padding-left: 30px;\">Beschreiben Sie kurz, was in dem Prozess enthalten ist und was nicht in den Prozessumfang f\u00e4llt bzw. was nicht darin enthalten ist.<\/p>\n<h4>Schritt 3: Erkl\u00e4ren Sie die Prozessgrenzen<\/h4>\n<p style=\"padding-left: 30px;\">Wo beginnt und wo endet der Prozess? Wodurch wird sie ausgel\u00f6st? Und woher wissen Sie, wann es fertig ist? Legen Sie diese Grenzen genau fest.<\/p>\n<h4>Schritt 4: Identifizieren Sie die Prozess-Outputs<\/h4>\n<p style=\"padding-left: 30px;\">Legen Sie fest, was durch den Prozess produziert werden soll oder welches Ergebnis der Prozess nach seinem Abschluss erzielen soll.<\/p>\n<h4>Schritt 5: Identifizieren Sie die Prozess-Inputs<\/h4>\n<p style=\"padding-left: 30px;\">Listen Sie auf, welche Ressourcen zur Durchf\u00fchrung der einzelnen Prozessschritte erforderlich sind.<\/p>\n<h4>Schritt 6: Brainstorming zu den Prozessschritten<\/h4>\n<p style=\"padding-left: 30px;\">Sammeln Sie alle Informationen zu den Prozessschritten von Anfang bis Ende. Beginnen Sie entweder mit dem, was den Prozess ausl\u00f6st, oder beginnen Sie am Ende des Prozesses und verfolgen Sie die Schritte bis zum Ausgangspunkt zur\u00fcck.<\/p>\n<p style=\"padding-left: 30px;\">An der Brainstorming-Sitzung sollten diejenigen teilnehmen, die direkt f\u00fcr die Prozessaufgaben verantwortlich sind oder jemanden, der sich damit auskennt, da sie pr\u00e4zise Daten liefern k\u00f6nnen.<\/p>\n<h4>Schritt 7: Organisieren Sie die Schritte der Reihe nach<\/h4>\n<p style=\"padding-left: 30px;\">Nehmen Sie die Liste der Schritte, die Sie sich ausgedacht haben, und bringen Sie sie in eine bestimmte Reihenfolge, um einen Prozessablauf zu erstellen.<\/p>\n<p style=\"padding-left: 30px;\">Beschr\u00e4nken Sie die Anzahl der Schritte auf ein Minimum, und wenn ein Schritt mehr als eine Aufgabe umfasst, f\u00fchren Sie diese unter dem Hauptschritt auf.<\/p>\n<h4>Schritt 8: Beschreiben Sie, wer involviert ist<\/h4>\n<p style=\"padding-left: 30px;\">Legen Sie fest, wer f\u00fcr die einzelnen <strong>Prozessaufgaben verantwortlich ist<\/strong>. Definieren Sie ihre Rollen. Vergessen Sie nicht, die Berufsbezeichnung und nicht den Namen zu nennen.<\/p>\n<p style=\"padding-left: 30px;\">Nehmen Sie auch R\u00fccksicht auf <strong>die Personen, die auf das Dokument verweisen werden<\/strong>. Schreiben Sie sie so, dass jeder Mitarbeiter mit einem angemessenen Kenntnisstand sie lesen und verstehen kann.<\/p>\n<h4>Schritt 9: Visualisieren Sie den Prozess<\/h4>\n<p style=\"padding-left: 30px;\">Dies dient der besseren \u00dcbersichtlichkeit und Lesbarkeit Ihrer Dokumentation. Stellen Sie die zuvor ermittelten Prozessschritte in einem Prozessablaufdiagramm \u00fcbersichtlich dar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15287\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Support-Process-Swimlane.png\" alt=\"Beispiel f\u00fcr ein Prozessablaufdiagramm mit Schwimmspuren \" width=\"1230\" height=\"735\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Support-Process-Swimlane.png 1230w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Support-Process-Swimlane-300x179.png 300w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Support-Process-Swimlane-1024x612.png 1024w\" sizes=\"auto, (max-width: 1230px) 100vw, 1230px\" \/><\/p>\n<h4>Schritt 10: Ausnahmen vom normalen Prozessablauf beachten<\/h4>\n<p style=\"padding-left: 30px;\">Ein Gesch\u00e4ftsprozess folgt aus verschiedenen Gr\u00fcnden nicht immer dem gleichen Ablauf. Nennen Sie diese Ausnahmen und welche Schritte unternommen werden, um sie zu beheben.<\/p>\n<h4>Schritt 11: Kontrollpunkte und Messungen hinzuf\u00fcgen<\/h4>\n<p style=\"padding-left: 30px;\">Ermitteln Sie, wo im Prozess Risiken auftreten k\u00f6nnten, und f\u00fcgen Sie Kontrollpunkte hinzu, um den Prozessverantwortlichen bei der \u00dcberwachung des Prozesses zu unterst\u00fctzen.<\/p>\n<p style=\"padding-left: 30px;\">Einf\u00fchrung von Messverfahren, um die Wirksamkeit des Prozesses zu ermitteln und ihn zu verbessern.<\/p>\n<h4>Schritt 12: \u00dcberpr\u00fcfung und Test des Prozesses<\/h4>\n<p style=\"padding-left: 30px;\">Versammeln Sie alle Beteiligten und \u00fcberpr\u00fcfen Sie das von Ihnen erstellte Prozessablaufdiagramm. Gibt es irgendwelche fehlenden Schritte? Ist alles in Ordnung? Testen Sie anschlie\u00dfend, ob Sie etwas \u00fcbersehen haben.<\/p>\n<h3><a name=\"Tips\"><\/a>Tipps und Tricks: Bew\u00e4hrte Praktiken der Prozessdokumentation<\/h3>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Halten Sie das Dokument <\/span><b>einfach und pr\u00e4gnant<\/b><span style=\"font-weight: 400;\">. Es sollte zwar <\/span><b>technisch genau<\/b><span style=\"font-weight: 400;\"> sein, aber auch <\/span><b>leicht verst\u00e4ndlich<\/b><span style=\"font-weight: 400;\">.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Es sollte ein geeigneter <\/span><b>Plan zur Aktualisierung der Dokumente vorhanden<\/b><span style=\"font-weight: 400;\"> sein, wenn sich der Prozess \u00e4ndert. Achten Sie darauf, <\/span><b>es mindestens einmal im Jahr zu \u00fcberpr\u00fcfen<\/b><span style=\"font-weight: 400;\">.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sie k\u00f6nnen auch<\/span><b> einen Prozessverantwortlichen zuweisen<\/b><span style=\"font-weight: 400;\">, der regelm\u00e4\u00dfige \u00dcberpr\u00fcfungen vornehmen und andere \u00fcber die \u00c4nderungen informieren kann.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>F\u00fchren Sie<\/b><span style=\"font-weight: 400;\"> f\u00fcr jeden Prozess eine <\/span><b>eigene Dokumentation<\/b><span style=\"font-weight: 400;\">, um Verwechslungen zu vermeiden.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Wenn Sie Prozesse zum ersten Mal dokumentieren, vermeiden Sie es, die gesamte Organisation auf einmal zu erfassen. <\/span><b>Beginnen Sie mit einem einzelnen Prozess innerhalb einer Abteilung <\/b><span style=\"font-weight: 400;\">oder einem wichtigen Prozess, der f\u00fcr die gesamte Organisation gilt.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Bewahren Sie die Dokumente an einem Ort auf, der f\u00fcr jeden, der danach sucht, <\/span><b>leicht zug\u00e4nglich <\/b><span style=\"font-weight: 400;\">ist.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Stellen Sie sicher, dass es bei Bedarf <\/span><b>leicht \u00fcberarbeitet werden kann <\/b><span style=\"font-weight: 400;\">und die neue Version <\/span><b>leicht<\/b><span style=\"font-weight: 400;\"> an alle Beteiligten <\/span><b>verteilt werden<\/b><span style=\"font-weight: 400;\"> kann.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Lassen Sie Dokumente \u00fcber ein Prozessdokumentationstool <\/span><b>online an einem zentralen Ort speichern<\/b><span style=\"font-weight: 400;\">. Dies hilft automatisch bei den beiden oben genannten bew\u00e4hrten Verfahren.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Verwenden Sie bei Bedarf geeignete <\/span><b>Beispiele, Grafiken, Farbkodierungen, Screenshots, mehrere Plattformen<\/b><span style=\"font-weight: 400;\"> usw.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Vergewissern Sie sich, dass die Prozessdokumentation <\/span><b>mit den bestehenden Standards Ihrer Organisation \u00fcbereinstimmt.<\/b><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Wenn Sie den Prozessablauf in verbaler Form erl\u00e4utern, sollten Sie <\/span><b>dies immer durch Grafiken &#8211; <\/b><span style=\"font-weight: 400;\">ein Prozessablaufdiagramm &#8211; <\/span><b>erg\u00e4nzen<\/b><span style=\"font-weight: 400;\">.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>F\u00fcgen Sie Ihren Gesch\u00e4ftsprozess-Flussdiagrammen Swimlanes hinzu<\/b><span style=\"font-weight: 400;\">, um zwischen verschiedenen Prozessrollen, Zeitpl\u00e4nen usw. zu unterscheiden.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Erstellen Sie einen Leitfaden f\u00fcr die Prozessdokumentation<\/b><span style=\"font-weight: 400;\">, den jeder als Standardvorlage f\u00fcr die Dokumentation eines Prozesses verwenden kann.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Nutzen Sie vorhandenes Dokumentationsmaterial<\/b><span style=\"font-weight: 400;\">, Aufzeichnungen, Interviews, Fallstudien, Feldtageb\u00fccher von Projektmitarbeitern und das Wissen der Mitarbeiter, um Informationen f\u00fcr die Prozessdokumentation zu sammeln.<\/span><\/li>\n<\/ul>\n<h3><a name=\"You\"><\/a><b>Was ist f\u00fcr Sie drin? Vorteile der Prozessdokumentation<\/b><\/h3>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Helfen Sie dabei, alle Beteiligten auf die gleiche Seite zu bringen, indem Sie <\/span><b>eine gemeinsame Ansicht der Prozessschritte<\/b><span style=\"font-weight: 400;\"> bereitstellen. Eine gemeinsame Sichtweise ist f\u00fcr die <\/span><b>Koh\u00e4renz<\/b><span style=\"font-weight: 400;\"> notwendig.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Wenn es eine<\/span><a href=\"https:\/\/www.heflo.com\/blog\/process-documentation\/business-process-documentation-best-practices\/\"> <span style=\"font-weight: 400;\">klare Prozessdokumentation<\/span><\/a><span style=\"font-weight: 400;\"> gibt, <\/span><b>k\u00f6nnen \u00c4nderungen an den Prozessen zeitnah und unkompliziert vorgenommen werden.<\/b><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Die Prozessdokumentation hilft bei der Ermittlung idealer Bedingungen f\u00fcr eine <\/span><b>effektive Zusammenarbeit und Leistung<\/b><span style=\"font-weight: 400;\">.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sie hilft auch bei der <\/span><b>Ermittlung von Engp\u00e4ssen und Ineffizienzen in Prozessen<\/b><span style=\"font-weight: 400;\"> (selbst in &#8220;ausgefeilten&#8221; Verfahren), die sonst m\u00f6glicherweise unbemerkt bleiben.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ein klar dokumentierter Prozess <\/span><b>spart Zeit und verhindert Fehler<\/b><span style=\"font-weight: 400;\">, indem er Unklarheiten beseitigt und klare Anweisungen gibt.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Reduziert Kosten und unn\u00f6tige Ausgaben von Ressourcen<\/b><span style=\"font-weight: 400;\">.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Tr\u00e4gt zur<\/span><b> Verbesserung der Gesamtqualit\u00e4t der Prozesse<\/b><span style=\"font-weight: 400;\"> und der Qualit\u00e4t der Ergebnisse bei.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Steigert <\/span><b>die Produktivit\u00e4t und die Zufriedenheit der Mitarbeiter<\/b><span style=\"font-weight: 400;\">.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Da klar festgehalten wird, wie die Prozesse ablaufen sollen, ist es <\/span><b>einfacher, Arbeiten auszulagern.<\/b><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Die Prozessdokumentation tr\u00e4gt auch dazu bei, dass <\/span><b>Prozesse<\/b><span style=\"font-weight: 400;\"> bei Bedarf <\/span><b>leicht automatisiert werden<\/b><span style=\"font-weight: 400;\"> k\u00f6nnen.<\/span><\/li>\n<\/ul>\n<h3><a name=\"Templates\"><\/a><b>Easy-Starter-Prozessdokumentationsvorlagen<\/b><\/h3>\n<p><strong><span style=\"font-weight: 400;\">Im Grunde genommen hilft<\/span><b> die<\/b><a href=\"https:\/\/creately.com\/de\/lp\/prozessmodellierung-software\/\"> <b>Prozessabbildung<\/b><\/a><span style=\"font-weight: 400;\"> dabei, die dokumentierten Informationen wie Prozessschritte, Prozessrollen, Inputs und Outputs in einem <\/span><b>rationalisierten Bild<\/b><span style=\"font-weight: 400;\"> darzustellen. Nachfolgend finden Sie Vorlagen f\u00fcr Prozessablaufdiagramme\/Prozessabbildungen, die Sie schnell online mit Informationen \u00fcber Ihre organisatorischen Prozesse bearbeiten k\u00f6nnen. Klicken Sie auf die Vorlage, um sie im Creately-Editor zu \u00f6ffnen. <\/span><\/strong><\/p>\n<p><strong>Vorlage 1<\/strong><\/p>\n<div id=\"attachment_18040\" style=\"width: 2180px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/creately.com\/demo-start?tempId=jhafhjdh\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-18040\" class=\"wp-image-18040 size-full\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/Untitled-Document-4.png\" alt=\"Beispiel f\u00fcr ein Prozessablaufdiagramm\" width=\"2170\" height=\"1675\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/Untitled-Document-4.png 2170w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/Untitled-Document-4-300x232.png 300w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/Untitled-Document-4-1024x790.png 1024w\" sizes=\"auto, (max-width: 2170px) 100vw, 2170px\" \/><\/a><p id=\"caption-attachment-18040\" class=\"wp-caption-text\">Klicken Sie auf die Vorlage, um sie online zu bearbeiten<\/p><\/div>\n<p><strong>Vorlage 2 <\/strong><\/p>\n<div id=\"attachment_15289\" style=\"width: 985px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/creately.com\/creately-start?tempID=j274b8003\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-15289\" class=\"wp-image-15289 size-full\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Vertical-Swimlane-Flowchart-Template.png\" alt=\"Vertikale Schwimmspur-Flussdiagramm-Vorlage\" width=\"975\" height=\"395\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Vertical-Swimlane-Flowchart-Template.png 975w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Vertical-Swimlane-Flowchart-Template-300x122.png 300w\" sizes=\"auto, (max-width: 975px) 100vw, 975px\" \/><\/a><p id=\"caption-attachment-15289\" class=\"wp-caption-text\">Klicken Sie auf die Vorlage, um sie online zu bearbeiten<\/p><\/div>\n<p><strong>Vorlage 3 <\/strong><\/p>\n<div id=\"attachment_15290\" style=\"width: 844px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/creately.com\/demo-start?tempId=geu4qzpa1\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-15290\" class=\"wp-image-15290 size-full\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Shipment-process.png\" alt=\"Prozessdiagramm eines Versandvorgangs \" width=\"834\" height=\"375\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Shipment-process.png 834w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Shipment-process-300x135.png 300w\" sizes=\"auto, (max-width: 834px) 100vw, 834px\" \/><\/a><p id=\"caption-attachment-15290\" class=\"wp-caption-text\">Klicken Sie auf die Vorlage, um sie online zu bearbeiten<\/p><\/div>\n<p><strong>Vorlage 4<\/strong><\/p>\n<div id=\"attachment_15291\" style=\"width: 1320px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/creately.com\/demo-start?tempId=geqyowvc4\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-15291\" class=\"wp-image-15291 size-full\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Credit-Card-Transaction-Process.png\" alt=\"Prozess einer Kreditkartentransaktion\" width=\"1310\" height=\"1145\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Credit-Card-Transaction-Process.png 1310w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Credit-Card-Transaction-Process-300x262.png 300w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/New-Credit-Card-Transaction-Process-1024x895.png 1024w\" sizes=\"auto, (max-width: 1310px) 100vw, 1310px\" \/><\/a><p id=\"caption-attachment-15291\" class=\"wp-caption-text\">Klicken Sie auf die Vorlage, um sie online zu bearbeiten<\/p><\/div>\n<h3><b>Feedback zum Easy Guide zur Prozessdokumentation<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Dieser Leitfaden zur Prozessdokumentation enth\u00e4lt alles, was Sie wissen m\u00fcssen, um einen Prozess richtig zu dokumentieren. Befolgen Sie die Schritte zur Prozessdokumentation, die wir oben besprochen haben, und nutzen Sie die Vorlagen f\u00fcr Prozessablaufdiagramme, um einen qualitativ hochwertigen Dokumentationsprozess zu gew\u00e4hrleisten. In unserer Community finden Sie weitere<\/span><a href=\"https:\/\/creately.com\/diagram-community\/examples\/t\/flowchart?pg=1\"> <span style=\"font-weight: 400;\">Vorlagen f\u00fcr Prozessablaufdiagramme<\/span><\/a><span style=\"font-weight: 400;\">. In unserem n\u00e4chsten Leitfaden werden wir Techniken zur Prozessverbesserung er\u00f6rtern, mit denen Sie Ihre Gesch\u00e4ftsprozesse problemlos rationalisieren k\u00f6nnen.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit dem Wachstum Ihres Unternehmens w\u00e4chst auch dessen Komplexit\u00e4t. Es sind mehr Schritte, mehr Personen und mehr Dinge involviert, die nicht immer auf die effizienteste Weise arrangiert werden k\u00f6nnen. Es mag entmutigend klingen, die Arbeitsweise Ihres Unternehmens zu \u00fcberdenken, aber&#8230;<span class=\"continue-reading\"> <a href=\"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/\">Read More<\/a><\/span><\/p>\n","protected":false},"author":38,"featured_media":15302,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3143],"tags":[5656,5658,5657,5659],"class_list":["post-24709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diagramme","tag-geschaftsprozess","tag-leitfaden-zur-prozessdokumentation","tag-prozessdokumentation","tag-prozessplan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leitfaden zur Prozessdokumentation: Erfahren Sie, wie Sie Prozesse dokumentieren<\/title>\n<meta name=\"description\" content=\"Ein detaillierter Leitfaden zur Prozessdokumentation, der die Bedeutung der Prozessdokumentation, die Dokumentation von Prozessen und Prozessdokumentvorlagen f\u00fcr den Start behandelt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leitfaden zur Prozessdokumentation: Erfahren Sie, wie Sie Prozesse dokumentieren\" \/>\n<meta property=\"og:description\" content=\"Ein detaillierter Leitfaden zur Prozessdokumentation, der die Bedeutung der Prozessdokumentation, die Dokumentation von Prozessen und Prozessdokumentvorlagen f\u00fcr den Start behandelt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/\" \/>\n<meta property=\"og:site_name\" content=\"Creately Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/creately\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-25T10:45:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-10T10:19:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/The-Easy-Guide-to-Process-Documentation.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1541\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lalindri Amunugama\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lalindri Amunugama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/\"},\"author\":{\"name\":\"Lalindri Amunugama\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#\\\/schema\\\/person\\\/cb4a421a55aa8a851260d92193524f26\"},\"headline\":\"Was ist Prozessdokumentation | Der einfache Leitfaden zur Prozessdokumentation\",\"datePublished\":\"2021-10-25T10:45:27+00:00\",\"dateModified\":\"2022-05-10T10:19:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/\"},\"wordCount\":1549,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2018\\\/01\\\/The-Easy-Guide-to-Process-Documentation.png\",\"keywords\":[\"Gesch\u00e4ftsprozess\",\"Leitfaden zur Prozessdokumentation\",\"Prozessdokumentation\",\"Prozessplan\"],\"articleSection\":[\"Diagramme\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/\",\"url\":\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/\",\"name\":\"Leitfaden zur Prozessdokumentation: Erfahren Sie, wie Sie Prozesse dokumentieren\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2018\\\/01\\\/The-Easy-Guide-to-Process-Documentation.png\",\"datePublished\":\"2021-10-25T10:45:27+00:00\",\"dateModified\":\"2022-05-10T10:19:11+00:00\",\"description\":\"Ein detaillierter Leitfaden zur Prozessdokumentation, der die Bedeutung der Prozessdokumentation, die Dokumentation von Prozessen und Prozessdokumentvorlagen f\u00fcr den Start behandelt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2018\\\/01\\\/The-Easy-Guide-to-Process-Documentation.png\",\"contentUrl\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2018\\\/01\\\/The-Easy-Guide-to-Process-Documentation.png\",\"width\":1541,\"height\":680,\"caption\":\"The Easy Guide to Process Documentation\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/de\\\/diagramme\\\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/creately.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was ist Prozessdokumentation | Der einfache Leitfaden zur Prozessdokumentation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/creately.com\\\/blog\\\/\",\"name\":\"Creately Blog\",\"description\":\"Latest Product Updates and Tips on Working Visually\",\"publisher\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/creately.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#organization\",\"name\":\"Creately\",\"url\":\"https:\\\/\\\/creately.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2023\\\/01\\\/creately-logo-symbol.png\",\"contentUrl\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2023\\\/01\\\/creately-logo-symbol.png\",\"width\":430,\"height\":237,\"caption\":\"Creately\"},\"image\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/creately\",\"https:\\\/\\\/x.com\\\/creately\",\"https:\\\/\\\/www.instagram.com\\\/creately_app\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#\\\/schema\\\/person\\\/cb4a421a55aa8a851260d92193524f26\",\"name\":\"Lalindri Amunugama\",\"url\":\"https:\\\/\\\/creately.com\\\/blog\\\/author\\\/lalindri\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leitfaden zur Prozessdokumentation: Erfahren Sie, wie Sie Prozesse dokumentieren","description":"Ein detaillierter Leitfaden zur Prozessdokumentation, der die Bedeutung der Prozessdokumentation, die Dokumentation von Prozessen und Prozessdokumentvorlagen f\u00fcr den Start behandelt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/","og_locale":"en_US","og_type":"article","og_title":"Leitfaden zur Prozessdokumentation: Erfahren Sie, wie Sie Prozesse dokumentieren","og_description":"Ein detaillierter Leitfaden zur Prozessdokumentation, der die Bedeutung der Prozessdokumentation, die Dokumentation von Prozessen und Prozessdokumentvorlagen f\u00fcr den Start behandelt.","og_url":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/","og_site_name":"Creately Blog","article_publisher":"https:\/\/www.facebook.com\/creately","article_published_time":"2021-10-25T10:45:27+00:00","article_modified_time":"2022-05-10T10:19:11+00:00","og_image":[{"width":1541,"height":680,"url":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/The-Easy-Guide-to-Process-Documentation.png","type":"image\/png"}],"author":"Lalindri Amunugama","twitter_misc":{"Written by":"Lalindri Amunugama","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/#article","isPartOf":{"@id":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/"},"author":{"name":"Lalindri Amunugama","@id":"https:\/\/creately.com\/blog\/#\/schema\/person\/cb4a421a55aa8a851260d92193524f26"},"headline":"Was ist Prozessdokumentation | Der einfache Leitfaden zur Prozessdokumentation","datePublished":"2021-10-25T10:45:27+00:00","dateModified":"2022-05-10T10:19:11+00:00","mainEntityOfPage":{"@id":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/"},"wordCount":1549,"commentCount":0,"publisher":{"@id":"https:\/\/creately.com\/blog\/#organization"},"image":{"@id":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/#primaryimage"},"thumbnailUrl":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/The-Easy-Guide-to-Process-Documentation.png","keywords":["Gesch\u00e4ftsprozess","Leitfaden zur Prozessdokumentation","Prozessdokumentation","Prozessplan"],"articleSection":["Diagramme"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/","url":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/","name":"Leitfaden zur Prozessdokumentation: Erfahren Sie, wie Sie Prozesse dokumentieren","isPartOf":{"@id":"https:\/\/creately.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/#primaryimage"},"image":{"@id":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/#primaryimage"},"thumbnailUrl":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/The-Easy-Guide-to-Process-Documentation.png","datePublished":"2021-10-25T10:45:27+00:00","dateModified":"2022-05-10T10:19:11+00:00","description":"Ein detaillierter Leitfaden zur Prozessdokumentation, der die Bedeutung der Prozessdokumentation, die Dokumentation von Prozessen und Prozessdokumentvorlagen f\u00fcr den Start behandelt.","breadcrumb":{"@id":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/#primaryimage","url":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/The-Easy-Guide-to-Process-Documentation.png","contentUrl":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2018\/01\/The-Easy-Guide-to-Process-Documentation.png","width":1541,"height":680,"caption":"The Easy Guide to Process Documentation"},{"@type":"BreadcrumbList","@id":"https:\/\/creately.com\/blog\/de\/diagramme\/was-ist-prozessdokumentation-der-einfache-leitfaden-zur-prozessdokumentation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/creately.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Was ist Prozessdokumentation | Der einfache Leitfaden zur Prozessdokumentation"}]},{"@type":"WebSite","@id":"https:\/\/creately.com\/blog\/#website","url":"https:\/\/creately.com\/blog\/","name":"Creately Blog","description":"Latest Product Updates and Tips on Working Visually","publisher":{"@id":"https:\/\/creately.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/creately.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/creately.com\/blog\/#organization","name":"Creately","url":"https:\/\/creately.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/creately.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2023\/01\/creately-logo-symbol.png","contentUrl":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2023\/01\/creately-logo-symbol.png","width":430,"height":237,"caption":"Creately"},"image":{"@id":"https:\/\/creately.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/creately","https:\/\/x.com\/creately","https:\/\/www.instagram.com\/creately_app\/"]},{"@type":"Person","@id":"https:\/\/creately.com\/blog\/#\/schema\/person\/cb4a421a55aa8a851260d92193524f26","name":"Lalindri Amunugama","url":"https:\/\/creately.com\/blog\/author\/lalindri\/"}]}},"_links":{"self":[{"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/posts\/24709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/comments?post=24709"}],"version-history":[{"count":3,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/posts\/24709\/revisions"}],"predecessor-version":[{"id":26819,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/posts\/24709\/revisions\/26819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/media\/15302"}],"wp:attachment":[{"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/media?parent=24709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/categories?post=24709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/tags?post=24709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}