{"id":24571,"date":"2021-12-15T16:57:02","date_gmt":"2021-12-15T05:57:02","guid":{"rendered":"https:\/\/creately.com\/blog\/?p=24571"},"modified":"2022-05-17T16:16:13","modified_gmt":"2022-05-17T05:16:13","slug":"o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis","status":"publish","type":"post","link":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/","title":{"rendered":"O guia f\u00e1cil para mapas de jornada do cliente com modelos edit\u00e1veis"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n<p class=\"wp-block-paragraph\">Melhor atendimento ao cliente, lealdade do cliente e aumento do ROI; 3 coisas que toda organiza\u00e7\u00e3o deseja poder alcan\u00e7ar da noite para o dia. \u00c9 poss\u00edvel, embora n\u00e3o da noite para o dia, mas com a ferramenta certa e esfor\u00e7o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma dessas ferramentas \u00e9 o<a href=\"https:\/\/creately.com\/pt\/lp\/software-de-mapeamento-da-jornada-do-cliente\"> mapa de jornada do cliente<\/a> e est\u00e1 l\u00e1 no topo com as outras ferramentas poderosas que ajudam a conduzir mudan\u00e7as focadas no cliente de forma eficaz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste guia, vamos explicar os passos que voc\u00ea precisa dar para criar um mapa de viagem do cliente que impulsione os resultados esperados, evitando os erros comuns que outros cometem.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>O que \u00e9 um Mapa de Jornada do Cliente?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">As expectativas dos clientes est\u00e3o em alta e continuar\u00e3o a crescer, for\u00e7ando as empresas a reinventarem-se constantemente para sobreviverem. Porqu\u00ea? A disponibilidade de m\u00faltiplos produtos e servi\u00e7os sob diferentes marcas e ofertas. Al\u00e9m disso, a presen\u00e7a de plataformas online, especialmente as redes sociais, tem dado maior controle sobre o cliente na tomada de decis\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 nesta situa\u00e7\u00e3o que o mapa de jornada do cliente se tornou t\u00e3o popular. Esta ferramenta, que tamb\u00e9m \u00e9 conhecida como o mapa de experi\u00eancia do cliente, visualiza a experi\u00eancia do cliente de uma organiza\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele representa cronologicamente cada passo da intera\u00e7\u00e3o que o cliente faz com o seu neg\u00f3cio. Um<a href=\"https:\/\/creately.com\/pt\/usage\/modelos-de-ferramentas-de-maquina\u00e7\u00e3o-de-trajecto-do-cliente\"> mapa de jornada do cliente<\/a> normalmente come\u00e7a com o passo inicial de quando o cliente descobre o seu produto\/servi\u00e7o e, dependendo do seu objetivo, pode prolongar-se pelo tempo que voc\u00ea quiser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Revela a\u00e7\u00f5es, emo\u00e7\u00f5es, pontos de dor e expectativas dos clientes ao longo da sua viagem. E ajuda a empresa a ver as coisas do ponto de vista do cliente, o que, por sua vez, ajuda a empresa a adquirir uma compreens\u00e3o profunda das necessidades do cliente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e1 muitos benef\u00edcios no mapeamento da jornada do cliente. Isso ajuda a:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Identificar as \u00e1reas em que o neg\u00f3cio deve priorizar o investimento e o esfor\u00e7o gastos<\/li><li>Obter informa\u00e7\u00f5es valiosas sobre o que o cliente espera de sua marca, suas motiva\u00e7\u00f5es internas e necessidades que, por sua vez, o ajudar\u00e3o a melhorar sua experi\u00eancia de cliente<\/li><li>Descobrir as lacunas entre as expectativas do cliente e a experi\u00eancia atual do cliente, utilizando o<a href=\"https:\/\/creately.com\/pt\/usage\/modelo-de-rater\"> Modelo RATER<\/a>.<\/li><li>Identificar problemas s\u00e9rios na experi\u00eancia do seu cliente e elimin\u00e1-los de forma proativa<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Como Criar um Mapa de Jornada do Cliente em 6 Passos<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Num relance, um<a href=\"https:\/\/creately.com\/pt\/lp\/software-de-mapeamento-da-jornada-do-cliente\"> mapa de jornada do cliente<\/a> pode parecer f\u00e1cil de fazer. Mas h\u00e1 muitos detalhes aos quais voc\u00ea precisa prestar aten\u00e7\u00e3o ao criar um. Nas etapas seguintes, simplificamos o processo de cria\u00e7\u00e3o de um mapa de jornada do cliente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma coisa que voc\u00ea precisa ter em mente \u00e9 que os mapas de viagem dos clientes podem diferir de empresa para empresa com base no produto\/servi\u00e7o que eles oferecem e no comportamento do p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m \u00e9 importante ter o tipo certo de pessoas que conhecem a experi\u00eancia do seu cliente na sala quando voc\u00ea est\u00e1 mapeando a viagem.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 1: Construa o seu Comprador Persona<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">A cria\u00e7\u00e3o de um mapa de jornada do cliente come\u00e7a com a defini\u00e7\u00e3o de seu comprador persona, que tra\u00e7a o perfil do seu cliente alvo com base em pesquisas extensivas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O comprador persona normalmente se baseia em dados demogr\u00e1ficos como idade, sexo, carreira, etc., al\u00e9m de outros detalhes comportamentais e psicogr\u00e1ficos como objetivos do cliente, interesses, estilo de vida, desafios, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O seu neg\u00f3cio pode ter um ou v\u00e1rios perfis de compradores, dependendo de quantos segmentos de p\u00fablico voc\u00ea est\u00e1 visando. E para evitar criar um mapa de jornada do cliente gen\u00e9rico demais, \u00e9 necess\u00e1rio criar mapas de jornada do cliente separados para cada um dos segmentos identificados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea tamb\u00e9m precisa ter cuidado para confiar em dados reais em vez de suposi\u00e7\u00f5es para evitar criar um perfil de cliente errado que n\u00e3o far\u00e1 muito por voc\u00ea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode reunir todos os dados que quiser a partir de pesquisas on-line, question\u00e1rios, pesquisas, feedback direto do cliente, entrevistas e com ferramentas como o Google Analytics.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqui est\u00e1 o nosso guia para<a href=\"https:\/\/creately.com\/blog\/diagrams\/how-to-create-a-buyer-persona\/\"> criar um comprador persona<\/a>. Consulte-o para criar seu pr\u00f3prio perfil de comprador em 4 passos simples. Comece com um modelo para poupar tempo.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/creately.com\/demo-start?tempId=6ufdRGfSuGB\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"701\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/B2C-Buyer-Persona-1024x701.png\" alt=\"Comprador Persona \" class=\"wp-image-17513\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/B2C-Buyer-Persona-1024x701.png 1024w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/B2C-Buyer-Persona-300x205.png 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption> Comprador Persona (Clique no modelo para edit\u00e1-lo online)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A cria\u00e7\u00e3o do<a href=\"https:\/\/creately.com\/pt\/lp\/criador-de-persona-de-usuario\"> comprador persona<\/a> tamb\u00e9m esclarecer\u00e1 os objetivos do comprador, o que \u00e9 outra coisa a que voc\u00ea precisa prestar aten\u00e7\u00e3o ao mapear a jornada de seu cliente.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 2: Mapeie as etapas do ciclo do cliente e os pontos de contato<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Quais s\u00e3o as etapas pelas quais o seu cliente passa para entrar em contato com o seu produto\/servi\u00e7o? A decomposi\u00e7\u00e3o do mapa de jornada do seu cliente em v\u00e1rias etapas facilitar\u00e1 a sua compreens\u00e3o e refer\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora, estas etapas podem variar dependendo da sua situa\u00e7\u00e3o comercial, design de funil de vendas, estrat\u00e9gias de marketing, etc., mas normalmente conteria &#8211; Conscientiza\u00e7\u00e3o, Considera\u00e7\u00e3o, Decis\u00e3o e Reten\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mapeie os pontos de contato para esclarecer ainda melhor os est\u00e1gios do ciclo de vida do cliente. Um ponto de contato refere-se a qualquer momento da sua jornada onde um cliente entra em contato com a sua marca (ou seja, website, redes sociais, testemunhos, an\u00fancios, pontos de venda, faturas, etc.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os dados que voc\u00ea coletou durante sua pesquisa de comprador persona dar\u00e3o a voc\u00ea uma boa id\u00e9ia sobre os pontos de contato do cliente ao longo das etapas do ciclo de vida; estes incluem os passos que eles tomam quando descobrem sua marca pela primeira vez para comprar seu produto e as intera\u00e7\u00f5es subsequentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Identificar todos os potenciais pontos de contato pode parecer esmagador, mas voc\u00ea pode sempre contar com ferramentas como o Google Analytics, que ir\u00e1 gerar relat\u00f3rios comportamentais (que mostram o caminho do usu\u00e1rio em todo o seu site) e relat\u00f3rios de fluxo de metas (que exibem o caminho que um usu\u00e1rio leva para completar uma convers\u00e3o de metas) para que voc\u00ea possa trabalhar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ou voc\u00ea pode seguir o m\u00e9todo tradicional e colocar-se no lugar dos seus clientes e fazer a sua jornada para identificar as a\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao mesmo tempo, tente determinar o estado emocional (encantado\/frustrado) do cliente enquanto ele toma cada a\u00e7\u00e3o. Saber como eles se sentem vai ajud\u00e1-lo a entender se eles v\u00e3o de uma etapa para a outra na jornada.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 3: Compreenda os Objetivos dos Clientes<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 aqui que voc\u00ea precisa focar sua aten\u00e7\u00e3o na compreens\u00e3o dos objetivos que seus clientes est\u00e3o tentando alcan\u00e7ar em cada etapa. Quando se trata de<a href=\"https:\/\/creately.com\/pt\/usage\/modelos-de-ferramentas-de-maquina\u00e7\u00e3o-de-trajecto-do-cliente\"> otimizar<\/a> a jornada do seu cliente, isso ajudar\u00e1 imensamente se voc\u00ea souber o que os seus clientes est\u00e3o a tentar alcan\u00e7ar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alguns m\u00e9todos que voc\u00ea pode usar aqui incluem respostas a question\u00e1rios, transcri\u00e7\u00f5es de entrevistas, e-mails de suporte ao cliente, testes com usu\u00e1rios, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma vez conhecidos os objetivos que os seus clientes est\u00e3o tentando alcan\u00e7ar em cada fase da jornada, pode alinh\u00e1-los com os pontos de contato.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 4: Identifique Obst\u00e1culos e Pontos de Dor do Cliente<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Agora voc\u00ea j\u00e1 sabe o que seu cliente est\u00e1 tentando alcan\u00e7ar em cada etapa do ciclo de vida do cliente, e cada um dos passos que ele d\u00e1 para que isso seja feito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Se a sua jornada de cliente fosse perfeita, ent\u00e3o voc\u00ea n\u00e3o teria seus clientes abandonando suas compras, deixando suas p\u00e1ginas de destino sem preencher os formul\u00e1rios, clicando no CTA apenas para fechar a aba, etc. Se a sua viagem n\u00e3o tivesse nenhum bloqueio na estrada, ent\u00e3o voc\u00ea n\u00e3o precisaria deste mapa de jornada do cliente em primeiro lugar. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas n\u00e3o \u00e9 esse o caso aqui, n\u00e3o \u00e9?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pode haver muitas coisas que est\u00e3o fazendo bem para que a experi\u00eancia do seu cliente seja suave, mas ainda pode haver muitos bloqueios que frustram os seus utilizadores. Nesta etapa, voc\u00ea precisa trabalhar para identificar quais s\u00e3o esses bloqueios e pontos de dor dos clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Talvez o pre\u00e7o do produto seja elevado demais, ou as taxas de envio n\u00e3o sejam razo\u00e1veis, ou talvez o formul\u00e1rio de registo seja longo demais. A identifica\u00e7\u00e3o de tais bloqueios de estrada ir\u00e1 ajud\u00e1-lo a aplicar as solu\u00e7\u00f5es adequadas para melhorar a sua experi\u00eancia do cliente. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode contar com os dados de pesquisa que voc\u00ea coletou para criar seus perfis de comprador aqui tamb\u00e9m.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 5: Identifique os Elementos em que Voc\u00ea Quer Focar<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Existem v\u00e1rios tipos de<a href=\"https:\/\/creately.com\/pt\/usage\/modelos-de-ferramentas-de-maquina\u00e7\u00e3o-de-trajecto-do-cliente\"> mapas de jornada do cliente<\/a> e cada um deles foca em uma variedade de elementos. Com base no seu prop\u00f3sito, voc\u00ea pode selecionar um deles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estado atual: <\/strong>Estes mapas mostram como os seus clientes est\u00e3o interagindo com a sua marca atualmente. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estado futuro:<\/strong> Este tipo de mapa visualiza as a\u00e7\u00f5es que voc\u00ea assume ou acredita que ser\u00e3o tomadas por seus clientes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dia na vida: <\/strong>Este tipo de mapa tenta capturar o que os seus clientes atuais ou potenciais clientes fazem num dia da sua vida. Eles revelar\u00e3o mais informa\u00e7\u00f5es sobre os seus clientes, incluindo pontos de dor na vida real.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 6: Repare os bloqueios de estrada<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Agora que conhece os problemas\/barreiras que os seus clientes encontram ao interagirem com a sua marca, concentre-se em dar prioridade e corrigi-los para melhorar cada ponto de contato para reter os clientes em todas as fases da jornada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os clientes est\u00e3o em constante mudan\u00e7a, assim como os seus mapas de jornada de clientes. Teste e atualize seus mapas de viagem de clientes quantas vezes necess\u00e1rio para refletir as mudan\u00e7as em seus clientes, bem como em seus produtos\/servi\u00e7os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqui est\u00e3o alguns modelos com os quais voc\u00ea pode come\u00e7ar imediatamente.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/creately.com\/demo-start?tempId=xsCFLo8jHiM\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"986\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/Customer-Journey-Map-Template-1-1024x986.png\" alt=\"Modelo do Mapa de Viagem do Cliente\" class=\"wp-image-17514\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/Customer-Journey-Map-Template-1-1024x986.png 1024w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/Customer-Journey-Map-Template-1-300x289.png 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption> Modelo de Mapa de Jornada do Cliente (Clique no modelo para edit\u00e1-lo online)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/creately.com\/demo-start?tempId=zB7yanBaRcs\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/Customer-Journey-Map-1-1024x574.png\" alt=\"Mapa de Viagem do Cliente\" class=\"wp-image-17515\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/Customer-Journey-Map-1-1024x574.png 1024w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/Customer-Journey-Map-1-300x168.png 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption> Mapa de Jornada do Cliente (Clique no modelo para edit\u00e1-lo online)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/creately.com\/demo-start?tempId=jji18vg42\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"462\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/Customer-Journey-Map-Template-1024x462.png\" alt=\"Modelo do Mapa de Viagem do Cliente \" class=\"wp-image-17516\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/Customer-Journey-Map-Template-1024x462.png 1024w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/Customer-Journey-Map-Template-300x135.png 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption> Modelo de Mapa de Jornada do Cliente (Clique no modelo para edit\u00e1-lo online)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/creately.com\/demo-start?tempId=jkw3k76eb\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"543\" src=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/Customer-Journey-Mapping-Template-1024x543.png\" alt=\"Modelo de Mapeamento da Viagem do Cliente \" class=\"wp-image-17517\" srcset=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/Customer-Journey-Mapping-Template-1024x543.png 1024w, https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/Customer-Journey-Mapping-Template-300x159.png 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption> Modelo de Mapeamento de Jornada do Cliente (Clique no modelo para edit\u00e1-lo online)<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pronto para Mapear a Jornada do Seu Cliente?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os mapas de jornada do cliente s\u00e3o uma \u00f3tima maneira de obter uma vis\u00e3o mais profunda sobre seus clientes e sua experi\u00eancia com sua organiza\u00e7\u00e3o. Leva tempo para entender como seus clientes interagem com voc\u00ea, o que eles sentem e o que eles querem alcan\u00e7ar e pode ser um longo caminho para mant\u00ea-los.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siga estes 6 passos para obter<a href=\"https:\/\/creately.com\/pt\/usage\/modelos-de-ferramentas-de-maquina\u00e7\u00e3o-de-trajecto-do-cliente\"> o mapa de jornada do seu cliente<\/a> corretamente. Use um modelo para poupar tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> E n\u00e3o se esque\u00e7a de deixar o seu feedback na se\u00e7\u00e3o de coment\u00e1rios abaixo. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Melhor atendimento ao cliente, lealdade do cliente e aumento do ROI; 3 coisas que toda organiza\u00e7\u00e3o deseja poder alcan\u00e7ar da noite para o dia. \u00c9 poss\u00edvel, embora n\u00e3o da noite para o dia, mas com a ferramenta certa e esfor\u00e7o&#8230;.<span class=\"continue-reading\"> <a href=\"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/\">Read More<\/a><\/span><\/p>\n","protected":false},"author":38,"featured_media":17520,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3274],"tags":[5748,5745,5746,5747,5749],"class_list":["post-24571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diagrama","tag-como-criar-um-mapa-da-jornada-do-cliente","tag-mapa-da-jornada-do-cliente","tag-mapeamento-da-jornada-do-cliente","tag-modelo-de-mapeamento-da-jornada-do-cliente","tag-o-que-e-um-mapa-da-jornada-do-cliente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como criar um mapa da jornada do cliente em 6 etapas f\u00e1ceis<\/title>\n<meta name=\"description\" content=\"Crie um mapa da jornada do cliente em 6 etapas r\u00e1pidas. Guia completo sobre mapeamento da jornada do cliente com modelos edit\u00e1veis para qualquer cen\u00e1rio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como criar um mapa da jornada do cliente em 6 etapas f\u00e1ceis\" \/>\n<meta property=\"og:description\" content=\"Crie um mapa da jornada do cliente em 6 etapas r\u00e1pidas. Guia completo sobre mapeamento da jornada do cliente com modelos edit\u00e1veis para qualquer cen\u00e1rio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/\" \/>\n<meta property=\"og:site_name\" content=\"Creately Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/creately\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-15T05:57:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-17T05:16:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/The-Easy-Guide-to-Customer-Journey-Maps-with-Editable-Templates.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1554\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lalindri Amunugama\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lalindri Amunugama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/\"},\"author\":{\"name\":\"Lalindri Amunugama\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#\\\/schema\\\/person\\\/cb4a421a55aa8a851260d92193524f26\"},\"headline\":\"O guia f\u00e1cil para mapas de jornada do cliente com modelos edit\u00e1veis\",\"datePublished\":\"2021-12-15T05:57:02+00:00\",\"dateModified\":\"2022-05-17T05:16:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/\"},\"wordCount\":1857,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2020\\\/01\\\/The-Easy-Guide-to-Customer-Journey-Maps-with-Editable-Templates.png\",\"keywords\":[\"como criar um mapa da jornada do cliente\",\"mapa da jornada do cliente\",\"mapeamento da jornada do cliente\",\"modelo de mapeamento da jornada do cliente\",\"o que \u00e9 um mapa da jornada do cliente\"],\"articleSection\":[\"diagrama\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/\",\"url\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/\",\"name\":\"Como criar um mapa da jornada do cliente em 6 etapas f\u00e1ceis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2020\\\/01\\\/The-Easy-Guide-to-Customer-Journey-Maps-with-Editable-Templates.png\",\"datePublished\":\"2021-12-15T05:57:02+00:00\",\"dateModified\":\"2022-05-17T05:16:13+00:00\",\"description\":\"Crie um mapa da jornada do cliente em 6 etapas r\u00e1pidas. Guia completo sobre mapeamento da jornada do cliente com modelos edit\u00e1veis para qualquer cen\u00e1rio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2020\\\/01\\\/The-Easy-Guide-to-Customer-Journey-Maps-with-Editable-Templates.png\",\"contentUrl\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2020\\\/01\\\/The-Easy-Guide-to-Customer-Journey-Maps-with-Editable-Templates.png\",\"width\":1554,\"height\":687,\"caption\":\"Guide to Customer Journey Mapping\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/pt\\\/diagrama\\\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/creately.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O guia f\u00e1cil para mapas de jornada do cliente com modelos edit\u00e1veis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/creately.com\\\/blog\\\/\",\"name\":\"Creately Blog\",\"description\":\"Latest Product Updates and Tips on Working Visually\",\"publisher\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/creately.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#organization\",\"name\":\"Creately\",\"url\":\"https:\\\/\\\/creately.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2023\\\/01\\\/creately-logo-symbol.png\",\"contentUrl\":\"https:\\\/\\\/d3n817fwly711g.cloudfront.net\\\/uploads\\\/2023\\\/01\\\/creately-logo-symbol.png\",\"width\":430,\"height\":237,\"caption\":\"Creately\"},\"image\":{\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/creately\",\"https:\\\/\\\/x.com\\\/creately\",\"https:\\\/\\\/www.instagram.com\\\/creately_app\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/creately.com\\\/blog\\\/#\\\/schema\\\/person\\\/cb4a421a55aa8a851260d92193524f26\",\"name\":\"Lalindri Amunugama\",\"url\":\"https:\\\/\\\/creately.com\\\/blog\\\/author\\\/lalindri\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como criar um mapa da jornada do cliente em 6 etapas f\u00e1ceis","description":"Crie um mapa da jornada do cliente em 6 etapas r\u00e1pidas. Guia completo sobre mapeamento da jornada do cliente com modelos edit\u00e1veis para qualquer cen\u00e1rio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/","og_locale":"en_US","og_type":"article","og_title":"Como criar um mapa da jornada do cliente em 6 etapas f\u00e1ceis","og_description":"Crie um mapa da jornada do cliente em 6 etapas r\u00e1pidas. Guia completo sobre mapeamento da jornada do cliente com modelos edit\u00e1veis para qualquer cen\u00e1rio.","og_url":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/","og_site_name":"Creately Blog","article_publisher":"https:\/\/www.facebook.com\/creately","article_published_time":"2021-12-15T05:57:02+00:00","article_modified_time":"2022-05-17T05:16:13+00:00","og_image":[{"width":1554,"height":687,"url":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/The-Easy-Guide-to-Customer-Journey-Maps-with-Editable-Templates.png","type":"image\/png"}],"author":"Lalindri Amunugama","twitter_misc":{"Written by":"Lalindri Amunugama","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/#article","isPartOf":{"@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/"},"author":{"name":"Lalindri Amunugama","@id":"https:\/\/creately.com\/blog\/#\/schema\/person\/cb4a421a55aa8a851260d92193524f26"},"headline":"O guia f\u00e1cil para mapas de jornada do cliente com modelos edit\u00e1veis","datePublished":"2021-12-15T05:57:02+00:00","dateModified":"2022-05-17T05:16:13+00:00","mainEntityOfPage":{"@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/"},"wordCount":1857,"commentCount":0,"publisher":{"@id":"https:\/\/creately.com\/blog\/#organization"},"image":{"@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/#primaryimage"},"thumbnailUrl":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/The-Easy-Guide-to-Customer-Journey-Maps-with-Editable-Templates.png","keywords":["como criar um mapa da jornada do cliente","mapa da jornada do cliente","mapeamento da jornada do cliente","modelo de mapeamento da jornada do cliente","o que \u00e9 um mapa da jornada do cliente"],"articleSection":["diagrama"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/","url":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/","name":"Como criar um mapa da jornada do cliente em 6 etapas f\u00e1ceis","isPartOf":{"@id":"https:\/\/creately.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/#primaryimage"},"image":{"@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/#primaryimage"},"thumbnailUrl":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/The-Easy-Guide-to-Customer-Journey-Maps-with-Editable-Templates.png","datePublished":"2021-12-15T05:57:02+00:00","dateModified":"2022-05-17T05:16:13+00:00","description":"Crie um mapa da jornada do cliente em 6 etapas r\u00e1pidas. Guia completo sobre mapeamento da jornada do cliente com modelos edit\u00e1veis para qualquer cen\u00e1rio.","breadcrumb":{"@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/#primaryimage","url":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/The-Easy-Guide-to-Customer-Journey-Maps-with-Editable-Templates.png","contentUrl":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2020\/01\/The-Easy-Guide-to-Customer-Journey-Maps-with-Editable-Templates.png","width":1554,"height":687,"caption":"Guide to Customer Journey Mapping"},{"@type":"BreadcrumbList","@id":"https:\/\/creately.com\/blog\/pt\/diagrama\/o-guia-facil-para-mapas-de-jornada-do-cliente-com-modelos-editaveis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/creately.com\/blog\/"},{"@type":"ListItem","position":2,"name":"O guia f\u00e1cil para mapas de jornada do cliente com modelos edit\u00e1veis"}]},{"@type":"WebSite","@id":"https:\/\/creately.com\/blog\/#website","url":"https:\/\/creately.com\/blog\/","name":"Creately Blog","description":"Latest Product Updates and Tips on Working Visually","publisher":{"@id":"https:\/\/creately.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/creately.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/creately.com\/blog\/#organization","name":"Creately","url":"https:\/\/creately.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/creately.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2023\/01\/creately-logo-symbol.png","contentUrl":"https:\/\/d3n817fwly711g.cloudfront.net\/uploads\/2023\/01\/creately-logo-symbol.png","width":430,"height":237,"caption":"Creately"},"image":{"@id":"https:\/\/creately.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/creately","https:\/\/x.com\/creately","https:\/\/www.instagram.com\/creately_app\/"]},{"@type":"Person","@id":"https:\/\/creately.com\/blog\/#\/schema\/person\/cb4a421a55aa8a851260d92193524f26","name":"Lalindri Amunugama","url":"https:\/\/creately.com\/blog\/author\/lalindri\/"}]}},"_links":{"self":[{"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/posts\/24571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/comments?post=24571"}],"version-history":[{"count":3,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/posts\/24571\/revisions"}],"predecessor-version":[{"id":27024,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/posts\/24571\/revisions\/27024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/media\/17520"}],"wp:attachment":[{"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/media?parent=24571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/categories?post=24571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/creately.com\/blog\/wp-json\/wp\/v2\/tags?post=24571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}